{"id":3679,"date":"2020-11-30T19:00:49","date_gmt":"2020-11-30T23:00:49","guid":{"rendered":"https:\/\/corpan.cl\/sitio\/?p=3679"},"modified":"2020-11-30T19:00:50","modified_gmt":"2020-11-30T23:00:50","slug":"se-conformo-la-red-del-conocimiento-del-corredor-bioceanico-central","status":"publish","type":"post","link":"https:\/\/corpan.cl\/sitio\/se-conformo-la-red-del-conocimiento-del-corredor-bioceanico-central\/","title":{"rendered":"Se conform\u00f3 la Red del Conocimiento del Corredor Bioce\u00e1nico Central"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">La integran universidades y centros de investigaci\u00f3n de Chile, Argentina, Uruguay y Brasil. Buscan unificar estudios sobre infraestructura, tecnolog\u00eda y educaci\u00f3n, del megaproyecto. <\/h4>\n\n\n\n<p>Fuente: Periferiaciencia.com.ar &#8211; Argentina 30-11-2020<\/p>\n\n\n\n<p style=\"font-size:18px\">Un grupo de m\u00e1s de treinta universidades y centros de investigaci\u00f3n de Argentina, Uruguay, Brasil y Chile conformaron la Red del Corredor Bioce\u00e1nico Central (CBC) con el objetivo de unificar el conocimiento alrededor del megaproyecto de integraci\u00f3n, desarrollo y de exportaciones del Cono Sur.&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">El acuerdo entre las casas de altos estudios apunta a unificar los estudios y desarrollos que se hacen en relaci\u00f3n al Corredor Bioce\u00e1nico Central en materia de infraestructura, tecnolog\u00eda, educaci\u00f3n, entre otros.&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">Lo har\u00e1n propiciando intercambios de estudiantes, docentes e investigaciones, con el fin de \u00abque la innovaci\u00f3n puesta al servicio del desarrollo territorial es la que permite el desarrollo sustentable de los pueblos\u00bb.&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">Por su parte, se destac\u00f3 la importancia del volumen de exportaciones de servicios empresariales entre los pa\u00edses del CBC, haciendo referencia principalmente a las consultar\u00edas profesionales, t\u00e9cnicas, y de otros. All\u00ed se remarc\u00f3 el potencial de desarrollo que tienen las universidades involucradas.&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">Para cerrar, se adelant\u00f3 que se trabaja en un pr\u00f3ximo encuentro hacia marzo de 2021, y en la puesta en marcha de plataformas tecnol\u00f3gicas de relacionamiento permanente a fin de favorecer el intercambiando, las alianzas y las diferentes vinculaciones entre instituciones educativas y de investigaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">De este primer encuentro participaron m\u00e1s de 60 representantes de instituciones educativas universitarias y de centros de estudios e investigaci\u00f3n de entidades empresariales tales como: la Universidad Abierta Interamericana; la Universidad del Centro Educativo Latinoamericano; la Universidad Cat\u00f3lica del Norte; la Universidad Nacional de Rosario; la Universidad Siglo 21; la Universidad Santo Tom\u00e1s, la Universidad de Concepci\u00f3n del Uruguay; la Universidad Cat\u00f3lica de Cuyo; el ICDA de la Universidad Cat\u00f3lica de C\u00f3rdoba; la Universidad de Vale do Rio dos Sinos (Unisinos); la Universidad de la Cuenca del Plata; la Universidad Tecnol\u00f3gica Nacional &#8211; Facultad Regional Rosario, la Universidad Cat\u00f3lica de Santa Fe; la Universidad Nacional del Nordeste; la universidad Tecnol\u00f3gica de Paran\u00e1; la Universidad Aut\u00f3noma de Entre R\u00edos; el Foro Empresario de la Regi\u00f3n Centro Argentina; la Corporaci\u00f3n Regional de Desarrollo Productivo de Chile; el ProChile; la Bolsa de Comercio de C\u00f3rdoba; la Federaci\u00f3n Empresarial de Corrientes; la Corporaci\u00f3n Paso Agua Negra (CORPAN); C\u00e1mara Industrias C\u00e1rnicas de Entre R\u00edos; el Centro Tecnol\u00f3gico del Mueble de Ca\u00f1ada de G\u00f3mez; Idom Consulting; la Federaci\u00f3n Empresarial de Corrientes; la Federaci\u00f3n Econ\u00f3mica de Entre R\u00edos; la Bolsa de Comercio de Rosario; la Bolsa de Cereales de Entre R\u00edos; Confederaciones Rurales (Cartez); la Asociaci\u00f3n para el Desarrollo de Concordia; la C\u00e1mara Empresaria del Autotransporte de Carga de C\u00f3rdoba; Coninagro y la Asociaci\u00f3n de Entidades Empresarias del Sur Santafesino. La coordinaci\u00f3n de la Red del Conocimiento est\u00e1 a cargo de la Corporaci\u00f3n Regional de Desarrollo Productivo de Chile, del Foro de Entidades Empresarias de la Regi\u00f3n Centro Argentina, de la Confederaci\u00f3n de C\u00e1maras Empresarias del Uruguay y del Comit\u00e9 de Rutas de Integraci\u00f3n de Am\u00e9rica del Sur. (APFDigital)&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\"><strong>El Corredor Bioce\u00e1nico&nbsp;<\/strong><\/p>\n\n\n\n<p style=\"font-size:18px\">El Corredor Bioce\u00e1nico Central es un \u00e1rea que recorre la zona centro de Chile y Argentina y que integra a Brasil y Uruguay y que fue pensada para facilitar la integraci\u00f3n, las exportaciones y el desarrollo del Cono Sur.&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">Est\u00e1 dentro de tres conjuntos principales que se interrelacionan entre s\u00ed: la regi\u00f3n de influencia de la Cordillera de los Andes, la Hidrov\u00eda Paraguay-Paran\u00e1 (HPP) y el Corredor Bioce\u00e1nico Central (CBC).&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\"><strong>Regi\u00f3n Cordillerana&nbsp;<\/strong><\/p>\n\n\n\n<p style=\"font-size:18px\">La regi\u00f3n cordillerana presenta una importante riqueza minera, energ\u00e9tica y forestal y especiales condiciones medioambientales para la producci\u00f3n frutihort\u00edcola y vitivin\u00edcola en los valles formados entre sus pliegues, con la ventaja log\u00edstica de la cercan\u00eda de los puertos sobre la costa del Pac\u00edfico, en el marco de los numerosos tratados de integraci\u00f3n que Chile logr\u00f3 forjar a lo largo de los \u00faltimos a\u00f1os. &nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">El t\u00fanel de Agua Negra, que facilita el transporte de las mercader\u00edas provenientes de los territorios mediterr\u00e1neos con destino a exportaci\u00f3n, especialmente aquellas enviadas a los pa\u00edses asi\u00e1ticos.&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\"><strong>Hidrov\u00eda Paraguay-Paran\u00e1&nbsp;<\/strong><\/p>\n\n\n\n<p style=\"font-size:18px\">Por \u00faltimo, la Hidrov\u00eda Paraguay-Paran\u00e1, se considera un \u00e1rea donde se emplaza una de las tierras agropecuarias m\u00e1s f\u00e9rtiles del mundo (Pampa H\u00fameda), se asienta la segunda cuenca hidrogr\u00e1fica m\u00e1s extensa y caudalosa de Sudam\u00e9rica (Cuenca del Plata), una de las principales reservas de agua dulce del planeta (Acu\u00edfero Guaran\u00ed) y el mayor humedal del mundo (El Pantanal).&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">Adem\u00e1s, en su radio de influencia se ubica, entre otros recursos, una importante reserva mundial de mineral de hierro (El Mut\u00fan). Para que sea conveniente despachar la oferta exportable por los puertos del Pac\u00edfico, los productos deben tener un alto valor por unidad de volumen y ser posible su transporte por ferrocarril a fin de reducir la incidencia del flete sobre su costo de comercializaci\u00f3n1&nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">El Corredor Bioce\u00e1nico Central une los dos ejes y facilita, a trav\u00e9s de su infraestructura, la salida de la producci\u00f3n por los puertos del Atl\u00e1ntico y el Pac\u00edfico. &nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">Su definici\u00f3n termin\u00f3 de plasmarse con los estudios y propuestas realizados a partir de los Ejes de Integraci\u00f3n y Desarrollo de la Iniciativa para la Integraci\u00f3n de la Infraestructura Regional (IIRSA), establecidos luego de la Primera Reuni\u00f3n de Presidentes en la Cumbre de las Am\u00e9ricas durante el a\u00f1o 2000. &nbsp;<\/p>\n\n\n\n<p style=\"font-size:18px\">All\u00ed se delimitaron cinco corredores bioce\u00e1nicos, uniendo los dos oc\u00e9anos a diferentes latitudes, desde la Patagonia en el sur hasta el l\u00edmite con la Cuenca del Amazonas en el norte. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La integran universidades y centros de investigaci\u00f3n de Chile, Argentina, Uruguay y Brasil. Buscan unificar estudios sobre infraestructura, tecnolog\u00eda y educaci\u00f3n, del megaproyecto. Fuente: Periferiaciencia.com.ar &#8211; Argentina 30-11-2020 Un grupo de m\u00e1s de treinta universidades y centros de investigaci\u00f3n de Argentina, Uruguay, Brasil y Chile conformaron la Red del Corredor Bioce\u00e1nico Central (CBC) con el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83,48,86,65,87,79,67,49,47,66,40,43,82,39,38,70,42,74,44,78,76,1],"tags":[],"class_list":["post-3679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agua-negra-deep-experiment-site","category-binacional","category-ciencia","category-cobre","category-corpan","category-corredor-bioceanico-coquimbo-porto-alegre","category-economia","category-educacion-superior","category-encuentro","category-exportaciones","category-informacion","category-jornadas","category-laboratorio-andes","category-noticias","category-paso-agua-negra","category-politica","category-region-de-coquimbo","category-san-juan-argentina","category-seminarios-y-congresos","category-sinergia","category-tunel-de-agua-negra","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/posts\/3679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/comments?post=3679"}],"version-history":[{"count":1,"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/posts\/3679\/revisions"}],"predecessor-version":[{"id":3682,"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/posts\/3679\/revisions\/3682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/media\/3681"}],"wp:attachment":[{"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/media?parent=3679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/categories?post=3679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corpan.cl\/sitio\/wp-json\/wp\/v2\/tags?post=3679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}